{"id":3328,"date":"2023-05-19T12:07:06","date_gmt":"2023-05-19T10:07:06","guid":{"rendered":"https:\/\/circolarte.it\/online\/?p=3328"},"modified":"2024-04-30T12:12:25","modified_gmt":"2024-04-30T10:12:25","slug":"caccia-al-libro-in-collaborazione-con-la-gilda-dei-custodi-pagina37","status":"publish","type":"post","link":"https:\/\/circolarte.it\/online\/caccia-al-libro-in-collaborazione-con-la-gilda-dei-custodi-pagina37\/","title":{"rendered":"Caccia al libro in collaborazione con La Gilda Dei Custodi | Pagina37"},"content":{"rendered":"<p>Chi trova un libro trova un Tesoro!<br \/>\nIn collaborazione con La Gilda dei Custodi di Storie e in occasione del <a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz  _aa9_ _a6hd\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.instagram.com\/explore\/tags\/salto23\/\">#SalTo23<\/a>, abbiamo organizzato una nuova Caccia al Libro!<\/p>\n<p>Oggi, Venerd\u00ec 19 Maggio, alcuni libri sono gi\u00e0 stati nascosti nei vari Padiglioni!\ud83d\udc40 Altri libri verranno nascosti domani!<\/p>\n<p>\ud83d\udccdDove? Al Salone del Libro di Torino!<\/p>\n<p>\ud83c\udf9f\ufe0f Non hai ancora il biglietto per entrare al SalTo? Abbiamo l&#8217;occasione giusta per te!<\/p>\n<p>Oggi 19 maggio alle ore 18:30 in Piazza Carlo Alberto (se piove Galleria Subalpina) puoi partecipare alla Caccia al libro organizzata in collaborazione con SaloneOff e tra i libri nascosti sono stati inseriti ben <strong>4 ingressi omaggio<\/strong> per il Salone del Libro di Torino! Non perdere questa occasione!<\/p>\n<p><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz  _aa9_ _a6hd\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.instagram.com\/explore\/tags\/furbochilegge\/\">#furbochilegge<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi trova un libro trova un Tesoro! In collaborazione con La Gilda dei Custodi di Storie e in occasione del #SalTo23, abbiamo organizzato una nuova Caccia al Libro! Oggi, Venerd\u00ec&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[300,301,302,182,136,25],"class_list":["post-3328","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-caccia-al-libro-digitale","tag-salone-off","tag-salone-del-libro","tag-pagina37","tag-torino","tag-circolarte"],"_links":{"self":[{"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/posts\/3328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/comments?post=3328"}],"version-history":[{"count":1,"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/posts\/3328\/revisions"}],"predecessor-version":[{"id":3329,"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/posts\/3328\/revisions\/3329"}],"wp:attachment":[{"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/media?parent=3328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/categories?post=3328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/circolarte.it\/online\/wp-json\/wp\/v2\/tags?post=3328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}